{"id":323,"date":"2024-05-03T10:33:25","date_gmt":"2024-05-03T13:33:25","guid":{"rendered":"https:\/\/motoyamaeferreira.com.br\/?page_id=323"},"modified":"2024-12-04T17:19:17","modified_gmt":"2024-12-04T20:19:17","slug":"contato","status":"publish","type":"page","link":"https:\/\/motoyamaeferreira.com.br\/index.php\/contato\/","title":{"rendered":"Contato"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"323\" class=\"elementor elementor-323\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63dde69f e-con-full e-flex e-con e-parent\" data-id=\"63dde69f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:24}},&quot;sticky&quot;:&quot;top&quot;,&quot;background_motion_fx_opacity_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-33c6d632 e-con-full e-flex e-con e-child\" data-id=\"33c6d632\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36061203 elementor-widget elementor-widget-image\" data-id=\"36061203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/elementor\/thumbs\/MOTOYAMA-E-FERREIRA-ADVOGADOS-05-e1713222233566-qn7zmx5expo2whnt24cvsrid00akz9pqtufeh5a6zo.png\" title=\"MOTOYAMA-E-FERREIRA-ADVOGADOS-05-e1713222233566.png\" alt=\"MOTOYAMA-E-FERREIRA-ADVOGADOS-05-e1713222233566.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4391d7dd e-con-full e-flex e-con e-child\" data-id=\"4391d7dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88b556e elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"88b556e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-88b556e\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-117\"><a href=\"https:\/\/motoyamaeferreira.com.br\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-118\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/sobre\/\" class=\"elementor-item\">Sobre<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-119\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/advogados\/\" class=\"elementor-item\">Advogados<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-120\"><a href=\"https:\/\/motoyamaeferreira.com.br\/#atuacao\" class=\"elementor-item elementor-item-anchor\">\u00c1reas de Atua\u00e7\u00e3o<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-121\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/artigos-juridicos\/\" class=\"elementor-item\">Artigos Jur\u00eddicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-236\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/category\/noticias\/\" class=\"elementor-item\">Not\u00edcias<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-122\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/contato\/\" class=\"elementor-item\">Contato<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-88b556e\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-117\"><a href=\"https:\/\/motoyamaeferreira.com.br\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-118\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/sobre\/\" class=\"elementor-item\" tabindex=\"-1\">Sobre<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-119\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/advogados\/\" class=\"elementor-item\" tabindex=\"-1\">Advogados<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-120\"><a href=\"https:\/\/motoyamaeferreira.com.br\/#atuacao\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u00c1reas de Atua\u00e7\u00e3o<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-121\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/artigos-juridicos\/\" class=\"elementor-item\" tabindex=\"-1\">Artigos Jur\u00eddicos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-236\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/category\/noticias\/\" class=\"elementor-item\" tabindex=\"-1\">Not\u00edcias<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-122\"><a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/contato\/\" class=\"elementor-item\" tabindex=\"-1\">Contato<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48e34ad e-flex e-con-boxed e-con e-parent\" data-id=\"48e34ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e0b5834 e-con-full e-flex e-con e-child\" data-id=\"3e0b5834\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20e4cae9 elementor-headline--style-rotate elementor-widget elementor-widget-animated-headline\" data-id=\"20e4cae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;animation_type&quot;:&quot;slide&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;rotate_iteration_delay&quot;:2500}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline elementor-headline-animation-type-slide\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Entre em contato<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c05f847 e-flex e-con-boxed e-con e-parent\" data-id=\"4c05f847\" data-element_type=\"container\" data-e-type=\"container\" id=\"sobre\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a090eb5 e-con-full e-flex e-con e-child\" data-id=\"5a090eb5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-412ed338 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"412ed338\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e3d13d animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"46e3d13d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Preencha o formul\u00e1rio abaixo e entre em contato consoco imediatamente. Responderemos o mais breve poss\u00edvel<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-209cfb9 elementor-widget elementor-widget-wpforms\" data-id=\"209cfb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style id=\"wpforms-css-vars-elementor-widget-209cfb9\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-209cfb9 {\n\t\t\t\t--wpforms-field-text-color: #000000;\n--wpforms-label-color: #000000D9;\n--wpforms-button-border-radius: 10px;\n--wpforms-button-background-color: #54595F;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-567\"><form id=\"wpforms-form-567\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"567\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/323\" data-token=\"834e415e3b2e4f8fe423a46f2b5638c7\" data-token-time=\"1778676483\"><noscript class=\"wpforms-error-noscript\">Ative o JavaScript no seu navegador para preencher este formul\u00e1rio.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Ative o JavaScript no seu navegador para preencher este formul\u00e1rio.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-567-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-567-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-567-field_1-error\" required><label for=\"wpforms-567-field_1\" class=\"wpforms-field-sublabel after\">Nome<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-567-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-567-field_1-last-error\" required><label for=\"wpforms-567-field_1-last\" class=\"wpforms-field-sublabel after\">Sobrenome<\/label><\/div><\/div><\/fieldset><\/div>\t\t<div id=\"wpforms-567-field_6-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"6\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-567-field_6\" >\u00c1rea Mensagem Nome<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-567-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-567-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-567-field_2\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-567-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-567-field_2-error\" required><\/div><div id=\"wpforms-567-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-567-field_4\">Contato <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-567-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"(**) *****-****\" step=\"any\" aria-errormessage=\"wpforms-567-field_4-error\" required><\/div><div id=\"wpforms-567-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-567-field_5\">\u00c1rea de atua\u00e7\u00e3o <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-567-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Escolha a \u00e1rea para contato<\/option><option value=\"Direito Empresarial e Societ\u00e1rio\"  class=\"choice-1 depth-1\"  >Direito Empresarial e Societ\u00e1rio<\/option><option value=\"Direito Imobili\u00e1rio\"  class=\"choice-3 depth-1\"  >Direito Imobili\u00e1rio<\/option><option value=\"Direito Condominial\"  class=\"choice-4 depth-1\"  >Direito Condominial<\/option><option value=\"Direito Civil e Consumidor\"  class=\"choice-8 depth-1\"  >Direito Civil e Consumidor<\/option><option value=\"Direito de Fam\u00edlia e Sucess\u00f5es\"  class=\"choice-7 depth-1\"  >Direito de Fam\u00edlia e Sucess\u00f5es<\/option><option value=\"Direito do Trabalho\"  class=\"choice-6 depth-1\"  >Direito do Trabalho<\/option><option value=\"Direito Tribut\u00e1rio\"  class=\"choice-5 depth-1\"  >Direito Tribut\u00e1rio<\/option><option value=\"Planejamento Sucess\u00f3rio\"  class=\"choice-2 depth-1\"  >Planejamento Sucess\u00f3rio<\/option><option value=\"Media\u00e7\u00e3o, Concilia\u00e7\u00e3o e Arbitragem\"  class=\"choice-9 depth-1\"  >Media\u00e7\u00e3o, Concilia\u00e7\u00e3o e Arbitragem<\/option><\/select><\/div><div id=\"wpforms-567-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-567-field_3\">Mensagem <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-567-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-567-field_3-error\" required><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-567-field_6-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-567-field_6-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-567-field_6-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"567\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/pages\/323\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-567\" class=\"wpforms-submit\" data-alt-text=\"Enviando\u2026\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Carregando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4801da49 e-con-full e-flex e-con e-child\" data-id=\"4801da49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d562686 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d562686\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:contato@motoyamaeferreira.com.br\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">contato@motoyamaeferreira.com.br<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/551120531731\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(11) 2053-1731<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+551120531731\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(11) 2053-1731<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ece6c83 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"ece6c83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-6e195b0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-1fbb242\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b6109e5\" href=\"https:\/\/www.instagram.com\/motoyamaeferreira\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-c311d5e\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8154711 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8154711\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R. Francisco Rodrigues Seckler, 727 - Vila Taquari, S\u00e3o Paulo - SP, 08230-020<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74688328 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"74688328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/wa.me\/551120531731\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENTRE EM CONTATO CONOSCO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69df201b e-flex e-con-boxed e-con e-parent\" data-id=\"69df201b\" data-element_type=\"container\" data-e-type=\"container\" id=\"blog\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62e98361 e-flex e-con-boxed e-con e-child\" data-id=\"62e98361\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-597d08aa animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"597d08aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Publica\u00e7\u00f5es recentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61412903 animated-slow elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-invisible elementor-widget elementor-widget-posts\" data-id=\"61412903\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-588 post type-post status-publish format-standard hentry category-noticias entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2025\/02\/04\/itr-em-areas-urbanas\/\" >\n\t\t\t\tIm\u00f3veis utilizados na explora\u00e7\u00e3o de atividades rurais est\u00e3o sujeitos \u00e0 incid\u00eancia do ITR, independentemente de sua localiza\u00e7\u00e3o\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A 18\u00aa C\u00e2mara de Direito P\u00fablico do Tribunal de Justi\u00e7a de S\u00e3o Paulo (IJSP) manteve decis\u00e3o que declarou a nulidade da cobran\u00e7a de IPTU de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2025\/02\/04\/itr-em-areas-urbanas\/\" aria-label=\"Read more about Im\u00f3veis utilizados na explora\u00e7\u00e3o de atividades rurais est\u00e3o sujeitos \u00e0 incid\u00eancia do ITR, independentemente de sua localiza\u00e7\u00e3o\" tabindex=\"-1\" >\n\t\t\tLEIA MAIS \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de fevereiro de 2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-576 post type-post status-publish format-standard has-post-thumbnail hentry category-direito-processual-civil tag-cumprimento-de-sentenca tag-prescricao tag-prescricao-intercorrente tag-suspensao-da-execucao entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2025\/02\/03\/honorarios-advocaticios-e-o-principio-da-causalidade-da-extincao-da-execucao-e-cumprimento-de-sentenca-por-prescricao-intercorrente\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010.jpg\" class=\"attachment-full size-full wp-image-375\" alt=\"\" srcset=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010.jpg 1500w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-300x300.jpg 300w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-1024x1024.jpg 1024w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-150x150.jpg 150w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-768x768.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"width:100%;height:100%;max-width:1500px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2025\/02\/03\/honorarios-advocaticios-e-o-principio-da-causalidade-da-extincao-da-execucao-e-cumprimento-de-sentenca-por-prescricao-intercorrente\/\" >\n\t\t\t\tHonor\u00e1rios Advocat\u00edcios e o Princ\u00edpio da Causalidade da extin\u00e7\u00e3o da Execu\u00e7\u00e3o e Cumprimento de senten\u00e7a por prescri\u00e7\u00e3o intercorrente\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Autor: Marcelo Hideo Motoyama, S\u00f3cio da Motoyama e Ferreira sociedade de advogados, bacharel pela Universidade Bras Cubas ( Turma de 1987), P\u00f3s graduado em Direito<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2025\/02\/03\/honorarios-advocaticios-e-o-principio-da-causalidade-da-extincao-da-execucao-e-cumprimento-de-sentenca-por-prescricao-intercorrente\/\" aria-label=\"Read more about Honor\u00e1rios Advocat\u00edcios e o Princ\u00edpio da Causalidade da extin\u00e7\u00e3o da Execu\u00e7\u00e3o e Cumprimento de senten\u00e7a por prescri\u00e7\u00e3o intercorrente\" tabindex=\"-1\" >\n\t\t\tLEIA MAIS \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t3 de fevereiro de 2025\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-373 post type-post status-publish format-standard has-post-thumbnail hentry category-empresarial entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/recuperacao-de-creditos-tributarios-no-direito-empresarial-uma-estrategia-financeira-e-legal-essencial\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-scaled.jpg\" class=\"attachment-full size-full wp-image-380\" alt=\"\" srcset=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-scaled.jpg 2560w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-300x300.jpg 300w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-1024x1024.jpg 1024w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-150x150.jpg 150w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-768x768.jpg 768w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-1536x1536.jpg 1536w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-2048x2048.jpg 2048w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/portrait-professional-business-people-working-together-1-1568x1568.jpg 1568w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"width:100%;height:100%;max-width:2560px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/recuperacao-de-creditos-tributarios-no-direito-empresarial-uma-estrategia-financeira-e-legal-essencial\/\" >\n\t\t\t\tRecupera\u00e7\u00e3o de Cr\u00e9ditos Tribut\u00e1rios no Direito Empresarial: Uma Estrat\u00e9gia Financeira e Legal Essencial\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Introdu\u00e7\u00e3o: No cen\u00e1rio complexo do direito empresarial, a busca por estrat\u00e9gias que otimizem a gest\u00e3o financeira e contribuam para a sa\u00fade econ\u00f4mica das empresas \u00e9<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/recuperacao-de-creditos-tributarios-no-direito-empresarial-uma-estrategia-financeira-e-legal-essencial\/\" aria-label=\"Read more about Recupera\u00e7\u00e3o de Cr\u00e9ditos Tribut\u00e1rios no Direito Empresarial: Uma Estrat\u00e9gia Financeira e Legal Essencial\" tabindex=\"-1\" >\n\t\t\tLEIA MAIS \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 de maio de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-370 post type-post status-publish format-standard has-post-thumbnail hentry category-empresarial entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/contratos-empresariais-elementos-essenciais-para-relacoes-comerciais-solidas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-scaled.jpg\" class=\"attachment-full size-full wp-image-378\" alt=\"\" srcset=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-scaled.jpg 2560w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-300x300.jpg 300w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-1024x1024.jpg 1024w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-150x150.jpg 150w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-768x768.jpg 768w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-1536x1536.jpg 1536w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-2048x2048.jpg 2048w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/05\/close-up-woman-writing-clipboard-with-pen-1568x1568.jpg 1568w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"width:100%;height:100%;max-width:2560px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/contratos-empresariais-elementos-essenciais-para-relacoes-comerciais-solidas\/\" >\n\t\t\t\tContratos Empresariais: Elementos Essenciais para Rela\u00e7\u00f5es Comerciais S\u00f3lidas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Introdu\u00e7\u00e3o: No universo din\u00e2mico do direito empresarial, os contratos desempenham um papel vital na regula\u00e7\u00e3o das rela\u00e7\u00f5es comerciais, proporcionando seguran\u00e7a jur\u00eddica e delineando as responsabilidades<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/05\/16\/contratos-empresariais-elementos-essenciais-para-relacoes-comerciais-solidas\/\" aria-label=\"Read more about Contratos Empresariais: Elementos Essenciais para Rela\u00e7\u00f5es Comerciais S\u00f3lidas\" tabindex=\"-1\" >\n\t\t\tLEIA MAIS \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 de maio de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-empresarial entry\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/04\/24\/compliance-empresarial-o-pilar-etico-no-direito-empresarial-moderno\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010.jpg\" class=\"attachment-full size-full wp-image-375\" alt=\"\" srcset=\"https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010.jpg 1500w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-300x300.jpg 300w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-1024x1024.jpg 1024w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-150x150.jpg 150w, https:\/\/motoyamaeferreira.com.br\/wp-content\/uploads\/2024\/04\/2150917010-768x768.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"width:100%;height:100%;max-width:1500px;\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/04\/24\/compliance-empresarial-o-pilar-etico-no-direito-empresarial-moderno\/\" >\n\t\t\t\tCompliance Empresarial: O Pilar \u00c9tico no Direito Empresarial Moderno\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Introdu\u00e7\u00e3o: No cen\u00e1rio empresarial contempor\u00e2neo, onde a transpar\u00eancia e a responsabilidade ganham cada vez mais destaque, o compliance empresarial emerge como um pilar \u00e9tico essencial.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/04\/24\/compliance-empresarial-o-pilar-etico-no-direito-empresarial-moderno\/\" aria-label=\"Read more about Compliance Empresarial: O Pilar \u00c9tico no Direito Empresarial Moderno\" tabindex=\"-1\" >\n\t\t\tLEIA MAIS \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24 de abril de 2024\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\tNenhum coment\u00e1rio\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77a17a3b e-flex e-con-boxed e-con e-parent\" data-id=\"77a17a3b\" data-element_type=\"container\" data-e-type=\"container\" id=\"contato\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6356b2d4 e-con-full e-flex e-con e-child\" data-id=\"6356b2d4\" data-element_type=\"container\" data-e-type=\"container\" id=\"contato\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb9eab1 elementor-widget elementor-widget-heading\" data-id=\"5bb9eab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contato<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7ef62 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d7ef62\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:contato@motoyamaeferreira.com.br\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">contato@motoyamaeferreira.com.br<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/551120531731\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(11) 2053-1731<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+551120531731\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(11) 2053-1731<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec16dba elementor-widget elementor-widget-heading\" data-id=\"4ec16dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Redes sociais<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1258c5f8 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"1258c5f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-6e195b0\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-1fbb242\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-b6109e5\" href=\"https:\/\/www.instagram.com\/motoyamaeferreira\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-c311d5e\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64c24fe1 elementor-widget elementor-widget-heading\" data-id=\"64c24fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Endere\u00e7o<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-800e96 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"800e96\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R. Francisco Rodrigues Seckler, 727 - Vila Taquari, S\u00e3o Paulo - SP, 08230-020<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-281e3f56 e-con-full e-flex e-con e-child\" data-id=\"281e3f56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11abedff elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"11abedff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"323\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"11abedff\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome completo\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Digite seu e-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_f816c75 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f816c75\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_f816c75]\" id=\"form-field-field_f816c75\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Digite seu telefone\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_8771cd3 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8771cd3\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\t\u00c1rea\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_8771cd3]\" id=\"form-field-field_8771cd3\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"Selecione a \u00e1rea que deseja contato\">Selecione a \u00e1rea que deseja contato<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito Empresarial e Societ\u00e1rio\">Direito Empresarial e Societ\u00e1rio<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Planejamento Sucess\u00f3rio\">Planejamento Sucess\u00f3rio<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito Imobili\u00e1rio\">Direito Imobili\u00e1rio<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito Condominial\">Direito Condominial<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito Civil e Consumidor\">Direito Civil e Consumidor<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito de Fam\u00edlia e Sucess\u00f5es\">Direito de Fam\u00edlia e Sucess\u00f5es<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Media\u00e7\u00e3o, concilia\u00e7\u00e3o e arbitragem\">Media\u00e7\u00e3o, concilia\u00e7\u00e3o e arbitragem<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito do Trabalho\">Direito do Trabalho<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Direito Tribut\u00e1rio\">Direito Tribut\u00e1rio<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENVIAR<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f8f6729 e-con-full e-flex e-con e-parent\" data-id=\"7f8f6729\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cad6297 elementor-widget elementor-widget-google_maps\" data-id=\"3cad6297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Motoyama%20e%20Ferreira%20Sociedade%20de%20Advogados&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Motoyama e Ferreira Sociedade de Advogados\"\n\t\t\t\t\taria-label=\"Motoyama e Ferreira Sociedade de Advogados\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56c6a6fd e-flex e-con-boxed e-con e-parent\" data-id=\"56c6a6fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cf4e86c elementor-widget elementor-widget-text-editor\" data-id=\"2cf4e86c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Copyright 2024. Todos os Direitos Reservados. Motoyama &amp; Ferreira Sociedade de Advocacia. Desenvolvido por <a href=\"https:\/\/www.mrgdigital.com.br\">MRG Digital<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entre em contato Contato Preencha o formul\u00e1rio abaixo e entre em contato consoco imediatamente. Responderemos o mais breve poss\u00edvel Ative o JavaScript no seu navegador para preencher este formul\u00e1rio.Ative o JavaScript no seu navegador para preencher este formul\u00e1rio. Nome * NomeSobrenome E-mail *Contato *\u00c1rea de atua\u00e7\u00e3o *Escolha a \u00e1rea para contatoDireito Empresarial e Societ\u00e1rioDireito Imobili\u00e1rioDireito&hellip; <a class=\"more-link\" href=\"https:\/\/motoyamaeferreira.com.br\/index.php\/2024\/04\/24\/compliance-empresarial-o-pilar-etico-no-direito-empresarial-moderno\/\">Continuar lendo <span class=\"screen-reader-text\">Compliance Empresarial: O Pilar \u00c9tico no Direito Empresarial Moderno<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-323","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/pages\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":28,"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/pages\/323\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/pages\/323\/revisions\/573"}],"wp:attachment":[{"href":"https:\/\/motoyamaeferreira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}